{"id":881,"count":1,"description":"","link":"https:\/\/www.bu.edu\/policies\/keyword\/performance-evaluation\/","name":"performance evaluation","slug":"performance-evaluation","taxonomy":"r_policies_keyword","meta":[],"_links":{"self":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/keyword\/881"}],"collection":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/keyword"}],"about":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/taxonomies\/r_policies_keyword"}],"wp:post_type":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/policies?keyword=881"},{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/pages?keyword=881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}