{"id":268,"count":1,"description":"","link":"https:\/\/www.bu.edu\/policies\/keyword\/make-up\/","name":"make up","slug":"make-up","taxonomy":"r_policies_keyword","meta":[],"_links":{"self":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/keyword\/268"}],"collection":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/keyword"}],"about":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/taxonomies\/r_policies_keyword"}],"wp:post_type":[{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/policies?keyword=268"},{"href":"https:\/\/www.bu.edu\/policies\/wp-json\/wp\/v2\/pages?keyword=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}