{"id":74108,"date":"2019-01-30T16:53:02","date_gmt":"2019-01-30T21:53:02","guid":{"rendered":"https:\/\/www.bu.edu\/academics\/?page_id=74108"},"modified":"2026-03-06T21:51:04","modified_gmt":"2026-03-07T02:51:04","slug":"school-of-theatre","status":"publish","type":"page","link":"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/","title":{"rendered":"School of Theatre"},"content":{"rendered":"<table cellpadding=\"0\" cellspacing=\"0\" border=\"0\" class=\"programs\">\n<thead>\n<tr>\n<td>Program<\/td>\n<td>Degree Options<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Acting<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/acting\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/acting\">BFA<\/a><br \/>\n<a href=\"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/acting\" data-gc-link=\"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/acting\"><\/a><\/td>\n<\/tr>\n<tr>\n<td>Costume Design &amp; Production<\/td>\n<td><a href=\"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/costume-design-production\/bfa\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/costume-production\/bfa\">BFA<\/a><span>,\u00a0<a href=\"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/costume-design-production\/mfa-design\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/costume-design\/mfa\">MFA\u2013Costume Design<\/a>,\u00a0<\/span><a href=\"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/costume-design-production\/mfa-production\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/costume-production\/mfa\">MFA\u2013Costume Production<\/a><\/td>\n<\/tr>\n<tr>\n<td>Dance<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/minor-in-dance\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/minor-in-dance\">Minor<\/a><\/td>\n<\/tr>\n<tr>\n<td>Directing<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/directing\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/directing\">MFA<\/a><\/td>\n<\/tr>\n<tr>\n<td>Lighting Design<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/lighting-design\/bfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/lighting-design\/bfa\">BFA<\/a><span>, <\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/lighting-design\/mfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/lighting-design\/mfa\">MFA<\/a><\/td>\n<\/tr>\n<tr>\n<td>Musical Theatre<\/td>\n<td><a href=\"https:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/musical-theatre-concentration\/\"><span>Concentration<\/span><\/a><\/td>\n<\/tr>\n<tr>\n<td>Production Management<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/academics\/cfa\/programs\/production-management\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/academics\/cfa\/programs\/production-management\/\">MFA<\/a><\/td>\n<\/tr>\n<tr>\n<td>Scene Design<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/scene-design\/bfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/scene-design\/bfa\">BFA<\/a><span>, <\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/scene-design\/mfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/scene-design\/mfa\">MFA<\/a><span>, <\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/scene-design\/certificate\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/scene-design\/certificate\/\">Artisan Certificate\u2013Scene Painting<\/a><\/td>\n<\/tr>\n<tr>\n<td>Sound Design<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/sound-design\/bfa\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/sound-design\/bfa\/\">BFA<\/a><span>, <\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/sound-design\/mfa\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/sound-design\/mfa\/\">MFA<\/a><\/td>\n<\/tr>\n<tr>\n<td>Stage Management<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/stage-management\/bfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/stage-management\/bfa\">BFA<\/a><\/td>\n<\/tr>\n<tr>\n<td>Technical Production<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/technical-production\/bfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/technical-production\/bfa\">BFA<\/a><span>, <\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/technical-production\/mfa\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/technical-production\/mfa\">MFA<\/a><\/td>\n<\/tr>\n<tr>\n<td>Theatre Arts<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-arts\/bfa-design-production\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-arts\/bfa-design-production\">BFA\u2014Design &amp; Production<\/a><span>, <\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-arts\/bfa-performance\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-arts\/bfa-performance\">BFA\u2014Performance<\/a><span>,\u00a0<\/span><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-arts\/minor\/\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-arts\/minor\/\">Minor<\/a><\/td>\n<\/tr>\n<tr>\n<td>Theatre Education<\/td>\n<td><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-education\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/theatre-education\">MFA<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li data-gc-list-depth=\"1\" data-gc-list-style=\"bullet\"><a href=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/study-abroad-options-in-theatre\" data-gc-link=\"http:\/\/www.bu.edu\/academics\/cfa\/programs\/school-of-theatre\/study-abroad-options-in-theatre\">Study Abroad Options in Theatre<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Program Degree Options Acting BFA Costume Design &amp; Production BFA,\u00a0MFA\u2013Costume Design,\u00a0MFA\u2013Costume Production Dance Minor Directing MFA Lighting Design BFA, MFA Musical Theatre Concentration Production Management MFA Scene Design BFA, MFA, Artisan Certificate\u2013Scene Painting Sound Design BFA, MFA Stage Management BFA Technical Production BFA, MFA Theatre Arts BFA\u2014Design &amp; Production, BFA\u2014Performance,\u00a0Minor Theatre Education MFA Study Abroad [&hellip;]<\/p>\n","protected":false},"author":4502,"featured_media":0,"parent":201,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/pages\/74108"}],"collection":[{"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/users\/4502"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/comments?post=74108"}],"version-history":[{"count":35,"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/pages\/74108\/revisions"}],"predecessor-version":[{"id":99884,"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/pages\/74108\/revisions\/99884"}],"up":[{"embeddable":true,"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/pages\/201"}],"wp:attachment":[{"href":"https:\/\/www.bu.edu\/academics\/wp-json\/wp\/v2\/media?parent=74108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}